{"id":291,"date":"2023-04-05T15:10:23","date_gmt":"2023-04-05T12:10:23","guid":{"rendered":"http:\/\/eliteneoncup.com\/edition-4\/?page_id=291"},"modified":"2026-04-24T13:29:33","modified_gmt":"2026-04-24T10:29:33","slug":"facilities","status":"publish","type":"page","link":"https:\/\/eliteneoncup.com\/edition-4\/facilities\/","title":{"rendered":"Facilities"},"content":{"rendered":"[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1761215818600{padding-bottom: 30px !important;}&#8221;]\n<h2>Kicks Academy Athletic Center<\/h2>\n<p><span class=\"content_text_highlight\">Fields:<\/span><br \/>\nKIC | U12 | 1 (hybrid grass)<br \/>\nKIC | U12 | 2 (hybrid grass)<br \/>\nKIC | U10 | 1 (artificial last generation grass)<br \/>\nKIC | U10 | 2 (artificial last generation grass)<br \/>\nKIC | U10 | 3 (artificial last generation grass)<br \/>\nKIC | U10 | 4 (artificial last generation grass)[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4685,4686,4687,4688&#8243; layout=&#8221;constrained_fullwidth&#8221; item_spacing=&#8221;10px&#8221; gallery_style=&#8221;5&#8243; load_in_animation=&#8221;none&#8221; el_class=&#8221;inner_facilities_img_gallery&#8221;][nectar_gmap zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; size=&#8221;450&#8243; map_center_lat=&#8221;37.978109&#8243; map_center_lng=&#8221;23.931898&#8243; map_markers=&#8221;37.978109 | 23.931898&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1729759227374{padding-bottom: 30px !important;}&#8221;]\n<h2>Peania Athletic Center<\/h2>\n<p><span class=\"content_text_highlight\">Fields:<\/span><br \/>\nPAIANIA 1 (natural grass) &#8211; U12 | 1 | Gym, U12 | 2 | Gym<br \/>\nPAIANIA 2 (natural grass) &#8211; U12 | 3 | Captain, U12 | 4 | Captain<br \/>\nPAIANIA 3 (natural grass) &#8211; U12 | 5 | Cannon, U12 | 6 | Cannon<br \/>\nPAIANIA 4 (synthetic turf) &#8211; U12 | 7 | Artificial, U12 | 8 | Artificial[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;2330,2333,2331,2334,2332&#8243; layout=&#8221;constrained_fullwidth&#8221; item_spacing=&#8221;10px&#8221; gallery_style=&#8221;5&#8243; load_in_animation=&#8221;none&#8221; el_class=&#8221;inner_facilities_img_gallery&#8221;][nectar_gmap zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; size=&#8221;450&#8243; map_center_lat=&#8221;37.933758&#8243; map_center_lng=&#8221;23.858010&#8243; map_markers=&#8221;37.933758 | 23.858010&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1761216720514{padding-bottom: 30px !important;}&#8221;]\n<h2>Koropi Municipal Stadium &#8220;Antonis Priftis&#8221;<\/h2>\n<p><span class=\"content_text_highlight\">Fields:<\/span><br \/>\nKOR | U10 | 1 (natural grass)<br \/>\nKOR | U10 | 2 (natural grass)<br \/>\nKOR | U10 | 3 (natural grass)<br \/>\nKOR | U10 | 4 (natural grass)[\/vc_column_text][nectar_gmap zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; size=&#8221;450&#8243; map_center_lat=&#8221;37.90163821080337&#8243; map_center_lng=&#8221;23.879684046565647&#8243; map_markers=&#8221;37.90163821080337 | 23.879684046565647&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1761216601683{padding-bottom: 30px !important;}&#8221;]\n<h2>Fous De Foot<\/h2>\n<p><span class=\"content_text_highlight\">Fields:<\/span><br \/>\nFDF | U12 | 1 (synthetic grass)<br \/>\nFDF | U12 | 2 (synthetic grass)<br \/>\n[\/vc_column_text][nectar_gmap zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; size=&#8221;450&#8243; map_center_lat=&#8221;37.829750401824455&#8243; map_center_lng=&#8221;23.814245302081883&#8243; map_markers=&#8221;37.829750401824455 | 23.814245302081883&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1761216703813{padding-bottom: 30px !important;}&#8221;]\n<h2>Nea Makri Municipal Stadium<\/h2>\n<p><span class=\"content_text_highlight\">Fields:<\/span><br \/>\nNM | U12 | 1 (synthetic grass)<br \/>\nNM | U12 | 2 (synthetic grass)[\/vc_column_text][nectar_gmap zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; size=&#8221;450&#8243; map_center_lat=&#8221;38.09324707507559&#8243; map_center_lng=&#8221;23.97167036107932&#8243; map_markers=&#8221;38.09324707507559 | 23.97167036107932&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1761216951859{padding-bottom: 30px !important;}&#8221;]\n<h2>Rafina Municipal Stadium<\/h2>\n<p><span class=\"content_text_highlight\">Fields:<\/span><br \/>\nRAF | U12 | 1 (synthetic grass)<br \/>\nRAF | U12 | 2 (synthetic grass)[\/vc_column_text][nectar_gmap zoom=&#8221;18&#8243; enable_zoom=&#8221;1&#8243; marker_style=&#8221;default&#8221; size=&#8221;450&#8243; map_center_lat=&#8221;38.02030731354581&#8243; map_center_lng=&#8221;24.008636205960606&#8243; map_markers=&#8221;38.02030731354581 | 24.008636205960606&#8243;][\/vc_column][\/vc_row][vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243; tablet_text_alignment=&#8221;default&#8221; phone_text_alignment=&#8221;default&#8221; column_border_width=&#8221;none&#8221; column_border_style=&#8221;solid&#8221;][vc_column_text css=&#8221;.vc_custom_1688724053640{padding-bottom: 30px !important;}&#8221;]\n<h2>Athens, Greece<\/h2>\n<p>The tournament will be held in state-of-the-art facilities at various athletic centers in Athens, Greece. The facilities meet the highest standards while also offering spaces for fun and various activities.[\/vc_column_text][vc_gallery type=&#8221;image_grid&#8221; images=&#8221;4685,4686,4687,4688&#8243; layout=&#8221;constrained_fullwidth&#8221; item_spacing=&#8221;10px&#8221; gallery_style=&#8221;5&#8243; load_in_animation=&#8221;none&#8221; el_class=&#8221;inner_facilities_img_gallery&#8221;][\/vc_column][\/vc_row]\n","protected":false},"excerpt":{"rendered":"<p>[vc_row type=&#8221;in_container&#8221; full_screen_row_position=&#8221;middle&#8221; scene_position=&#8221;center&#8221; text_color=&#8221;dark&#8221; text_align=&#8221;left&#8221; top_padding=&#8221;60&#8243; bottom_padding=&#8221;60&#8243; class=&#8221;page_content_row&#8221; disable_element=&#8221;yes&#8221; overlay_strength=&#8221;0.3&#8243;][vc_column enable_animation=&#8221;true&#8221; animation=&#8221;fade-in-from-bottom&#8221; column_padding=&#8221;no-extra-padding&#8221; column_padding_position=&#8221;all&#8221; background_color_opacity=&#8221;1&#8243; background_hover_color_opacity=&#8221;1&#8243; column_shadow=&#8221;none&#8221; el_class=&#8221;page_content_column&#8221; width=&#8221;1\/1&#8243;&#8230;<\/p>\n","protected":false},"author":1,"featured_media":7,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-291","page","type-page","status-publish","has-post-thumbnail","hentry"],"_links":{"self":[{"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/pages\/291","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/comments?post=291"}],"version-history":[{"count":67,"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/pages\/291\/revisions"}],"predecessor-version":[{"id":14236,"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/pages\/291\/revisions\/14236"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/media\/7"}],"wp:attachment":[{"href":"https:\/\/eliteneoncup.com\/edition-4\/wp-json\/wp\/v2\/media?parent=291"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}